{"id":21,"count":3,"description":"","link":"http:\/\/digiteratech.com\/blog\/category\/internet-marketing\/","name":"Internet Marketing","slug":"internet-marketing","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/digiteratech.com\/blog\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/digiteratech.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/digiteratech.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/digiteratech.com\/blog\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}